{"id":201,"date":"2010-09-17T18:44:11","date_gmt":"2010-09-17T16:44:11","guid":{"rendered":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/?p=201"},"modified":"2010-09-17T18:45:21","modified_gmt":"2010-09-17T16:45:21","slug":"3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur","status":"publish","type":"post","link":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/","title":{"rendered":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur"},"content":{"rendered":"<p>3 vid\u00e9os !\u00a0\u00a03 jeunes mecs de 18 et 20 ans. Tout keuss et tr\u00e8s chaud de la bite, ils partagent avec nous l&rsquo;une de leurs branlettes ! La queue bien raide et gonfler de jus\u00a0, ils se masturbent et giclent en gros plan !!!! big \u00e9jac de sperme<br \/>\nTELECHARGES LES VIDEOS CLIQUE SUR LA JUTE DU MEC<br \/>\n<iframe name=\"ZonehotThumb\" src=\"http:\/\/www.zone-hot.com\/thumblink.php?ID=1096199008|73&#038;cat=vNEW&#038;size=XXL&#038;ref=boy154\" scrolling=\"no\" frameborder=\"no\" style=\"border:#000000 1px solid; width:640px; height:480px\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 vid\u00e9os !\u00a0\u00a03 jeunes mecs de 18 et 20 ans. Tout keuss et tr\u00e8s chaud de la bite, ils partagent avec nous l&rsquo;une de leurs branlettes ! La queue bien raide et gonfler de jus\u00a0, ils se masturbent et giclent en gros plan !!!! big \u00e9jac de sperme TELECHARGES LES VIDEOS CLIQUE SUR LA JUTE &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/\" class=\"more-link\">Continuer la lecture <span class=\"screen-reader-text\"> \u00ab\u00a03 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[51,15,22,58,62,61,31],"class_list":["post-201","post","type-post","status-publish","format-standard","hentry","category-masturbation","tag-ejac","tag-grosse-queue","tag-jeunes-mecs","tag-se-branler-entre-pote","tag-sperme","tag-vestiaire","tag-videos","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 jeunes sportifs english se branlent devant la cam\u00e9ra d&#039;un pote voyeur | Le blog photos des grosses bites sur Ma teub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&#039;un pote voyeur | Le blog photos des grosses bites sur Ma teub\" \/>\n<meta property=\"og:description\" content=\"3 vid\u00e9os !\u00a0\u00a03 jeunes mecs de 18 et 20 ans. Tout keuss et tr\u00e8s chaud de la bite, ils partagent avec nous l&rsquo;une de leurs branlettes ! La queue bien raide et gonfler de jus\u00a0, ils se masturbent et giclent en gros plan !!!! big \u00e9jac de sperme TELECHARGES LES VIDEOS CLIQUE SUR LA JUTE &hellip; Continuer la lecture \u00ab\u00a03 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog photos des grosses bites sur Ma teub\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-17T16:44:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-09-17T16:45:21+00:00\" \/>\n<meta name=\"author\" content=\"Actif TBM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Actif TBM\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/\"},\"author\":{\"name\":\"Actif TBM\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/#\\\/schema\\\/person\\\/08fdebca378f22a61f1d60d64f3585ea\"},\"headline\":\"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur\",\"datePublished\":\"2010-09-17T16:44:11+00:00\",\"dateModified\":\"2010-09-17T16:45:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/\"},\"wordCount\":65,\"commentCount\":0,\"keywords\":[\"\u00e9jac\",\"grosse queue\",\"jeunes mecs\",\"se branler entre pote\",\"sperme\",\"vestiaire\",\"vid\u00e9os\"],\"articleSection\":[\"Masturbation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/\",\"url\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/\",\"name\":\"3 jeunes sportifs english se branlent devant la cam\u00e9ra d'un pote voyeur | Le blog photos des grosses bites sur Ma teub\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/#website\"},\"datePublished\":\"2010-09-17T16:44:11+00:00\",\"dateModified\":\"2010-09-17T16:45:21+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/#\\\/schema\\\/person\\\/08fdebca378f22a61f1d60d64f3585ea\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/#website\",\"url\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/\",\"name\":\"Le blog photos des grosses bites sur Ma teub\",\"description\":\"Des gars nus sans complexes et sans pudeurs qui posent \u00e0 poils devant des photographes, la teub au repos ou en \u00e9rection\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/#\\\/schema\\\/person\\\/08fdebca378f22a61f1d60d64f3585ea\",\"name\":\"Actif TBM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g\",\"caption\":\"Actif TBM\"},\"sameAs\":[\"http:\\\/\\\/www.gay-tattoo.com\\\/\"],\"url\":\"http:\\\/\\\/www.mateub.com\\\/le-blog-des-grosses-bites\\\/author\\\/actif-tbm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d'un pote voyeur | Le blog photos des grosses bites sur Ma teub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/","og_locale":"fr_FR","og_type":"article","og_title":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d'un pote voyeur | Le blog photos des grosses bites sur Ma teub","og_description":"3 vid\u00e9os !\u00a0\u00a03 jeunes mecs de 18 et 20 ans. Tout keuss et tr\u00e8s chaud de la bite, ils partagent avec nous l&rsquo;une de leurs branlettes ! La queue bien raide et gonfler de jus\u00a0, ils se masturbent et giclent en gros plan !!!! big \u00e9jac de sperme TELECHARGES LES VIDEOS CLIQUE SUR LA JUTE &hellip; Continuer la lecture \u00ab\u00a03 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur\u00a0\u00bb","og_url":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/","og_site_name":"Le blog photos des grosses bites sur Ma teub","article_published_time":"2010-09-17T16:44:11+00:00","article_modified_time":"2010-09-17T16:45:21+00:00","author":"Actif TBM","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Actif TBM"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/#article","isPartOf":{"@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/"},"author":{"name":"Actif TBM","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/#\/schema\/person\/08fdebca378f22a61f1d60d64f3585ea"},"headline":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur","datePublished":"2010-09-17T16:44:11+00:00","dateModified":"2010-09-17T16:45:21+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/"},"wordCount":65,"commentCount":0,"keywords":["\u00e9jac","grosse queue","jeunes mecs","se branler entre pote","sperme","vestiaire","vid\u00e9os"],"articleSection":["Masturbation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/","url":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/","name":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d'un pote voyeur | Le blog photos des grosses bites sur Ma teub","isPartOf":{"@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/#website"},"datePublished":"2010-09-17T16:44:11+00:00","dateModified":"2010-09-17T16:45:21+00:00","author":{"@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/#\/schema\/person\/08fdebca378f22a61f1d60d64f3585ea"},"breadcrumb":{"@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/3-jeunes-sportifs-english-se-branlent-devant-la-camera-dun-pote-voyeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/"},{"@type":"ListItem","position":2,"name":"3 jeunes sportifs english se branlent devant la cam\u00e9ra d&rsquo;un pote voyeur"}]},{"@type":"WebSite","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/#website","url":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/","name":"Le blog photos des grosses bites sur Ma teub","description":"Des gars nus sans complexes et sans pudeurs qui posent \u00e0 poils devant des photographes, la teub au repos ou en \u00e9rection","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/#\/schema\/person\/08fdebca378f22a61f1d60d64f3585ea","name":"Actif TBM","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/224f071d0c9c64d69c2e99d27fa44286812a73b219729523b2fd094db9f431c2?s=96&d=monsterid&r=g","caption":"Actif TBM"},"sameAs":["http:\/\/www.gay-tattoo.com\/"],"url":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/author\/actif-tbm\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/posts\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":0,"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/posts\/201\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/media?parent=201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/categories?post=201"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mateub.com\/le-blog-des-grosses-bites\/wp-json\/wp\/v2\/tags?post=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}